{"id":228682,"date":"2019-07-07T08:18:11","date_gmt":"2019-07-07T06:18:11","guid":{"rendered":"https:\/\/www.liga3-online.de\/?p=228682"},"modified":"2019-07-07T08:18:11","modified_gmt":"2019-07-07T06:18:11","slug":"kraemer-im-interview-gibt-weltweit-keine-staerkere-3-liga","status":"publish","type":"post","link":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/2019\/07\/07\/kraemer-im-interview-gibt-weltweit-keine-staerkere-3-liga\/","title":{"rendered":"Kr\u00e4mer im Interview: &#34;Gibt weltweit keine st\u00e4rkere 3. Liga&#34;"},"content":{"rendered":"<p><strong>Im Interview mit liga3-online.de spricht Magdeburgs Trainer Stefan Kr\u00e4mer \u00fcber eine besondere Teambuilding-Ma\u00dfnahme beim FCM, die Zielsetzung f\u00fcr die neue Saison, die Favoriten auf den Aufstieg und die St\u00e4rke der 3. Liga.<\/strong><\/p>\n<p>[box type=&#34;info&#34;]<strong>&#34;Zielformulierung hat mir super gefallen&#34;<\/strong>[\/box]<\/p>\n<p><strong>liga3-online.de: Neuer Trainer, fast komplett neues Team: Nach dem Abstieg aus der 2. Bundesliga gab es beim 1. FC Magdeburg einen gro\u00dfen Umbruch. Wie homogen ist das Team bereits, Herr Kr\u00e4mer?<\/strong><\/p>\n<p><strong>Stefan Kr\u00e4mer:<\/strong> Wir haben die ersten Wochen ordentlich genutzt, um uns alle kennenzulernen. Das ist aber ein l\u00e4ngerer Prozess, der auch noch nicht abgeschlossen ist, wenn die Vorbereitung vorbei ist. Insgesamt denke ich, dass wir eine gute Mischung aus erfahrenen und jungen Spielern haben. Ich habe ein sehr gutes Gef\u00fchl. Wie schnell wir zusammenwachsen, h\u00e4ngt aber sicher auch davon ab, wie erfolgreich wir in die Saison starten.<\/p>\n<p><strong>Gab es besondere Ma\u00dfnahmen f\u00fcr das Teambuilding?<\/strong><\/p>\n<p>Wir waren unter anderem Fu\u00dfballgolf spielen, was allen viel Spa\u00df bereitet hat. F\u00fcr mich als Trainer besonders interessant war aber eine andere Einheit. W\u00e4hrend eines Wochenendtrips, bei dem wir jeweils einen alten und einen jungen Spieler in Bungalows untergebracht haben, hatten die Jungs die Aufgabe, Boote zu bauen und damit dann auf dem See ein Rennen zu fahren. Es war spannend zu sehen, wer beim Bootsbau die F\u00fchrungsrolle \u00fcbernimmt und wer nur das macht, was die anderen sagen. Ich konnte mir dabei ein gutes Bild von den Charaktereigenschaften der Spieler machen. Au\u00dferdem war es am\u00fcsant, mit anzusehen, wie die Jungs teilweise an der Challenge verzweifelt sind. (lacht) Ein Boot bauen sie ja nun einmal nicht jeden Tag.<\/p>\n<p><strong>Bis zum Saisonstart sind es noch rund zwei Wochen. Brauchen Sie diese Zeit auch noch oder k\u00f6nnte es jetzt schon losgehen, wenn es nach Ihnen ginge?<\/strong><\/p>\n<p>Wer mich kennt, wei\u00df, dass ich nicht gerne so lange auf den Saisonstart warte. Allerdings ist es grunds\u00e4tzlich aus Trainersicht nicht schlecht, die zwei Wochen noch zu haben. Die Spieler m\u00fcssen ja auch erst einmal verstehen, was ich von ihnen will. Dann ist es meine Aufgabe, zu schauen, ob meine Spielphilosophie \u00fcberhaupt zu den Jungs passt. Es macht keinen Sinn, zwingend die eigene Philosophie durchzudr\u00fccken. Man muss dazu bereit sein, die eigenen Ideen gegebenenfalls auch anzupassen.<\/p>\n<p><strong>Einmal mehr hat wohl die halbe Liga den Anspruch, oben mitzuspielen. Wie sieht die Zielsetzung des 1. FC Magdeburg aus?<\/strong><\/p>\n<p>Wir haben uns als Klub klar positioniert. Innerhalb von drei Jahren soll es wieder hoch in die 2. Bundesliga gehen. Diese Zielformulierung hat mir super gefallen, weil es einfach eine realistische Einsch\u00e4tzung der Situation ist. Nur weil man Absteiger ist, hei\u00dft das nicht, dass man automatisch direkt zu den Aufstiegsfavoriten geh\u00f6rt. Erfahrungsgem\u00e4\u00df kann es in beide Richtungen gehen, Eintracht Braunschweig ist beispielsweise in der letzten Saison nur knapp dem Abstieg entgangen. Wir m\u00fcssen erst einmal wieder in der 3. Liga ankommen. Keiner bei uns ist so blau\u00e4ugig und denkt, dass wir durch die Saison marschieren.<\/p>\n<p>&nbsp;<\/p>\n<p>[box type=&#34;info&#34;]<strong>&#34;3. Liga ist eine hervorragende Marke&#34;<\/strong>[\/box]<\/p>\n<p><strong>Welche drei Teams haben Ihrer Meinung nach die besten Karten auf den Aufstieg?<\/strong><\/p>\n<p>Um das zu prognostizieren, braucht man in dieser ausgeglichenen Liga eine Glaskugel. (lacht) Mit solchen Vorhersagen kann man komplett daneben liegen. Aber ich werde mich trotzdem mal f\u00fcr drei Teams entscheiden. Eintracht Braunschweig hat eine bockstarke R\u00fcckserie gespielt und gezeigt, welch immense Qualit\u00e4t im Team steckt. Ich denke, dass die Aufstiegschancen der Eintracht nicht schlecht stehen. Der 1. FC Kaiserslautern hat gro\u00dfe Anspr\u00fcche und eine riesige Fanbase im R\u00fccken, die die Mannschaft zum Wiederaufstieg tragen will. Auch meinem Ex-Klub KFC Uerdingen, der hochkar\u00e4tige Transfers get\u00e4tigt hat, traue ich einiges zu.<\/p>\n<p><strong>F\u00fcr Sie ist der 1. FC Magdeburg bereits die f\u00fcnfte Station in der 3. Liga, mit 200 Drittliga-Partien rangieren Sie in der Liste der Rekordtrainer hinter Peter Vollmann (237 Spiele) und Pavel Dotchev (210) auf Platz drei. Was ist die 3. Liga f\u00fcr Sie?<\/strong><\/p>\n<p>Die 3. Liga ist eine hervorragende Marke, die sich in den letzten Jahren enorm positiv entwickelt und sich in Deutschland als Profiliga etabliert hat. Vom Niveau und Zuschauerinteresse her ist sie nicht weit entfernt von der 2. Bundesliga. Nicht umsonst setzt sich in der Relegation zwischen der 2. und 3. Liga meist der Drittligist durch. Dass Zweitliga-Absteiger sich oft in der 3. Liga schwer tun, ist ein weiterer Beweis daf\u00fcr, dass die 2. Liga kaum st\u00e4rker ist. Im internationalen Vergleich w\u00fcrde ich behaupten, dass es weltweit keine st\u00e4rkere 3. Liga gibt. Vielleicht kann die englische League One mithalten, das war es dann aber auch schon. Ich bin absolut gl\u00fccklich, dass ich schon so lange in der 3. Liga t\u00e4tig bin und jetzt bei einem Traditionsverein in einer absolut fu\u00dfballverr\u00fcckten Stadt arbeiten darf.<\/p>\n<p><strong>Ihren letzten Verein KFC Uerdingen f\u00fchrten Sie in die 3. Liga. Trotz Platz vier und Chance auf den Durchmarsch in die 2. Bundesliga wurden Sie dann nach dem 21. Spieltag \u00fcberraschend freigestellt. Wie bewerten Sie diese Entscheidung r\u00fcckblickend?<\/strong><\/p>\n<p>Ich ma\u00dfe mir nicht an, meine Freistellung in Uerdingen zu bewerten. Der Vereinschef war der Meinung, dass es das Beste sei, den Trainer auszutauschen, um noch erfolgreicher zu werden. Diese Entscheidung musste ich hinnehmen. Mehr werde ich dazu nicht sagen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Interview mit liga3-online.de spricht Magdeburgs Trainer Stefan Kr\u00e4mer \u00fcber Teambuilding beim FCM, das Zielsetzung f\u00fcr die neue Saison, die Favoriten auf den Aufstieg und die St\u00e4rke der 3. Liga.<\/p>\n","protected":false},"author":11,"featured_media":228684,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,1,26],"tags":[],"_links":{"self":[{"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/wp\/v2\/posts\/228682"}],"collection":[{"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/wp\/v2\/comments?post=228682"}],"version-history":[{"count":0,"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/wp\/v2\/posts\/228682\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/wp\/v2\/media?parent=228682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/wp\/v2\/categories?post=228682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/wp\/v2\/tags?post=228682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}