{"id":228836,"date":"2019-07-08T16:48:26","date_gmt":"2019-07-08T14:48:26","guid":{"rendered":"https:\/\/www.liga3-online.de\/?p=228836"},"modified":"2019-07-08T16:48:26","modified_gmt":"2019-07-08T14:48:26","slug":"zwickau-verpflichtet-kanadischen-nationalspieler-marcus-godinho","status":"publish","type":"post","link":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/2019\/07\/08\/zwickau-verpflichtet-kanadischen-nationalspieler-marcus-godinho\/","title":{"rendered":"Zwickau verpflichtet kanadischen Nationalspieler Godinho"},"content":{"rendered":"<p><strong>Rund zwei Wochen vor dem Saisonauftakt hat der FSV Zwickau die gew\u00fcnschte Verst\u00e4rkung f\u00fcr die Defensive gefunden.\u00a0Marcus Godinho vom\u00a0schottischen Erstligisten Heart of Midlothian wechselt zu den Schw\u00e4nen und unterschrieb einen Vertrag bis 2021.<\/strong><\/p>\n<h3>Kanadischer Nationalspieler<\/h3>\n<p>Mit dem 22-j\u00e4hrigen Rechtsverteidiger angelt sich der FSV einen Nationalspieler. Viermal kam\u00a0Godinho bisher f\u00fcr Kanada zum Einsatz, zuletzt beim Gold Cup &#8211; der\u00a0Kontinentalmeisterschaft f\u00fcr Nord-, Mittelamerika und der Karibik. Dabei stand er dreimal auf dem Platz (jeweils \u00fcber die volle Distanz) und erreichte das Viertelfinale.<\/p>\n<p>Umso gr\u00f6\u00dfer ist die Freude bei FSV-Sportchef Toni Wachsmuth, dass sich der 23-J\u00e4hrige nun f\u00fcr Zwickau entschieden hat: &#34;Wir freuen uns, dass wir mit Marcus einen Rechtsverteidiger verpflichten konnten, der in der Viererkette und auch im Dreierkettensystem einsetzbar ist.&#34;\u00a0Godinho habe bereits\u00a0in der ersten schottischen Liga (16 Spiele, ein Tor, drei Vorlagen) und auch in der kanadischen A-Nationalmannschaft &#34;sehr gute Leistungen auf der Position gezeigt und wir sind davon \u00fcberzeugt, dass er das auch in der 3. Liga unter Beweis stellen kann&#34;, f\u00e4hrt\u00a0Wachsmuth fort.<\/p>\n<h3>Elfter Neuzugang<\/h3>\n<p>Der Zwickauer Sportchef sieht in Marcus Godinho auch ein &#34;neues Element&#34; auf der rechten Defensivposition: &#34;Marcus ist ein gelernter Rechtsverteidiger der sehr dynamisch Fu\u00dfball spielt, sowohl gegen den Ball, als auch mit dem Ball.&#34; Nun gehe es darum, den 23-J\u00e4hrigen\u00a0&#34;schnellstm\u00f6glich in die Mannschaft zu integrieren und die Belastung so zu steuern, dass er uns schnellstm\u00f6glich auf dem Feld zur Verf\u00fcgung stehen wird.&#34;<\/p>\n<p>Beim FSV Zwickau ist Godinho nach\u00a0Leon Jensen,\u00a0Ali Odabas,\u00a0Denis J\u00e4pel,\u00a0Christopher Handke,\u00a0Marius Hauptmann, Fabio Viteritti,\u00a0Maurice Hehne,\u00a0Gerrit Wegkamp,\u00a0Elias Huth und\u00a0Sascha H\u00e4rtel der elfte Neuzugang f\u00fcr die anstehende Saison.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rund zwei Wochen vor dem Saisonauftakt hat der FSV Zwickau die gew\u00fcnschte Verst\u00e4rkung f\u00fcr die Defensive gefunden.\u00a0Marcus Godinho vom\u00a0schottischen Erstligisten Heart of Midlothian wechselt zu den Schw\u00e4nen und unterschrieb einen Vertrag bis 2021.<\/p>\n","protected":false},"author":1,"featured_media":228837,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"_links":{"self":[{"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/wp\/v2\/posts\/228836"}],"collection":[{"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/wp\/v2\/comments?post=228836"}],"version-history":[{"count":0,"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/wp\/v2\/posts\/228836\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/wp\/v2\/media?parent=228836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/wp\/v2\/categories?post=228836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.liga2-online.de\/liga3-test\/index.php\/wp-json\/wp\/v2\/tags?post=228836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}